{"id":430,"date":"2017-10-23T03:25:53","date_gmt":"2017-10-23T03:25:53","guid":{"rendered":"http:\/\/thetrainerthailand.com\/home\/?p=430"},"modified":"2022-04-16T08:09:51","modified_gmt":"2022-04-16T08:09:51","slug":"%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87","status":"publish","type":"post","link":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/","title":{"rendered":"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0   \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>&#8220;\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23<\/p>\n<p>\u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21<wbr \/>\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a<\/p>\n<p>\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4b\u0e4c\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e31\u0e27\u0e40<wbr \/>\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19&#8221;<\/p>\n<p>&#8211; The Go-Giver<\/p>\n<p><span class=\"text_exposed_show\"><br \/>\n\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e21\u0e31\u0e01\u0e14\u0e39\u0e16\u0e39\u0e01\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<wbr \/>\u0e40\u0e25\u0e47\u0e01\u0e46<\/span><\/p>\n<p><span class=\"text_exposed_show\"><br \/>\n\u0e41\u0e15\u0e48\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e15\u0e49\u0e19\u0e40\u0e2b\u0e15\u0e38<wbr \/>\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e17\u0e35\u0e48\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 !!!<\/span><\/p>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08 <a href=\"https:\/\/www.facebook.com\/MindsetPropertyByMin\"><strong>\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49<\/strong><\/a>\u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e17\u0e39\u0e1b\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCnzGgprXhTHkdWEcSdS9ZQw\/featured\"><strong>\u0e2a\u0e21\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32<\/strong><\/a>\u00a0\u0e41\u0e25\u0e30 \u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u00a0<strong><a href=\"https:\/\/www.thetrainerthailand.com\/\" rel=\"home\">\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07<\/a><\/strong><\/p>\n<p style=\"text-align: center;\">* * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * *<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04 <a class=\"read-more-link\" href=\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[4],"tags":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0  \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thetrainerthailand.com\/home\/\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0  \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand\" \/>\n<meta property=\"og:description\" content=\"&#8220;\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04 Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thetrainerthailand.com\/home\/\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\/\" \/>\n<meta property=\"og:site_name\" content=\"The Trainer Thailand\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-23T03:25:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-16T08:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1513\" \/>\n\t<meta property=\"og:image:height\" content=\"825\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e42\u0e1b\u0e40\u0e15\u0e49\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/\",\"name\":\"The Trainer Thailand\",\"description\":\"Property Dealer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#primaryimage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg\",\"contentUrl\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg\",\"width\":1513,\"height\":825},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#webpage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/\",\"name\":\"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand\",\"isPartOf\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#primaryimage\"},\"datePublished\":\"2017-10-23T03:25:53+00:00\",\"dateModified\":\"2022-04-16T08:09:51+00:00\",\"author\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\"},\"breadcrumb\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thetrainerthailand.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\",\"name\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"caption\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\"},\"url\":\"https:\/\/thetrainerthailand.com\/home\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0  \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thetrainerthailand.com\/home\/\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0  \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand","og_description":"&#8220;\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04 Read More","og_url":"https:\/\/thetrainerthailand.com\/home\/\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\/","og_site_name":"The Trainer Thailand","article_published_time":"2017-10-23T03:25:53+00:00","article_modified_time":"2022-04-16T08:09:51+00:00","og_image":[{"width":1513,"height":825,"url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Written by":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/thetrainerthailand.com\/home\/#website","url":"https:\/\/thetrainerthailand.com\/home\/","name":"The Trainer Thailand","description":"Property Dealer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#primaryimage","url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg","contentUrl":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2017\/10\/1-22.jpg","width":1513,"height":825},{"@type":"WebPage","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#webpage","url":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/","name":"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d - The Trainer Thailand","isPartOf":{"@id":"https:\/\/thetrainerthailand.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#primaryimage"},"datePublished":"2017-10-23T03:25:53+00:00","dateModified":"2022-04-16T08:09:51+00:00","author":{"@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d"},"breadcrumb":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%84%e0%b8%b8%e0%b8%93%e0%b8%88%e0%b8%b0%e0%b8%a1%e0%b8%b5%e0%b8%ad%e0%b8%b4%e0%b8%97%e0%b8%98%e0%b8%b4%e0%b8%9e%e0%b8%a5%e0%b8%a1%e0%b8%b2%e0%b8%81%e0%b9%80%e0%b8%9e%e0%b8%b5%e0%b8%a2%e0%b8%87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thetrainerthailand.com\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e04\u0e38\u0e13\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e32\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e44\u0e23\u00a0 \u0e01\u0e47\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d"}]},{"@type":"Person","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d","name":"\u0e42\u0e1b\u0e40\u0e15\u0e49","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","caption":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"url":"https:\/\/thetrainerthailand.com\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/430"}],"collection":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":2,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/430\/revisions"}],"predecessor-version":[{"id":6549,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/430\/revisions\/6549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media\/431"}],"wp:attachment":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/categories?post=430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/tags?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}