{"id":4500,"date":"2018-12-11T08:28:05","date_gmt":"2018-12-11T08:28:05","guid":{"rendered":"http:\/\/thetrainerthailand.com\/home\/?p=4500"},"modified":"2021-10-02T14:25:48","modified_gmt":"2021-10-02T14:25:48","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10","status":"publish","type":"post","link":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<h2>\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 <span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14464,&quot;10&quot;:2,&quot;14&quot;:[null,2,0],&quot;15&quot;:&quot;Tahoma&quot;,&quot;16&quot;:11}\">\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0<\/span>\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30<\/h2>\n<p>\u0e40\u0e27\u0e25\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e31\u0e01\u0e21\u0e32\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e47\u0e21\u0e31\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e33\u0e46 \u0e17\u0e33\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e17\u0e32\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e36\u0e07\u0e01\u0e47\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2b\u0e21\u0e14 \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e43\u0e0a\u0e49\u0e04\u0e23\u0e31\u0e49\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e01\u0e47\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e0b\u0e30\u0e01\u0e48\u0e2d\u0e19 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e17\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e01\u0e33\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e22\u0e01\u0e47\u0e04\u0e07\u0e44\u0e21\u0e48\u0e44\u0e2b\u0e27 \u0e08\u0e30\u0e02\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e04\u0e48\u0e04\u0e23\u0e36\u0e48\u0e07\u0e01\u0e33\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e04\u0e07\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e07\u0e15\u0e32\u0e40\u0e02\u0e35\u0e22\u0e27\u0e41\u0e19\u0e48\u0e46\u0e04\u0e48\u0e30 \u0e2d\u0e22\u0e32\u0e01\u0e2b\u0e32\u0e27\u0e34\u0e18\u0e35\u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e1c\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 <strong>\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14<\/strong> \u0e21\u0e35 \u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e44\u0e27\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e01\u0e31\u0e19\u0e08\u0e49\u0e32<\/p>\n<h3><img loading=\"lazy\" class=\"aligncenter wp-image-4502\" src=\"http:\/\/thetrainerthailand.com\/home\/\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium.jpg\" alt=\"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\" width=\"900\" height=\"576\" srcset=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium.jpg 700w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium-300x192.jpg 300w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium-500x320.jpg 500w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium-696x445.jpg 696w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/iStock_000013218508_Medium-656x420.jpg 656w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/h3>\n<h3>\u0e1c\u0e31\u0e01\u0e01\u0e32\u0e14\u0e41\u0e01\u0e49\u0e27, \u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35<\/h3>\n<p>\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01\u0e01\u0e32\u0e14\u0e41\u0e01\u0e49\u0e27\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e46 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e04\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e47\u0e07\u0e4a\u0e32\u0e22\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e21\u0e35\u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19 \u0e43\u0e0a\u0e49\u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19 3 \u0e2d\u0e31\u0e19\u0e1b\u0e31\u0e01\u0e25\u0e07\u0e44\u0e1b\u0e25\u0e36\u0e01\u0e46 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e02\u0e31\u0e49\u0e27 \u0e40\u0e27\u0e49\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e44\u0e1f\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e2a\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e31\u0e01\u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e02\u0e31\u0e49\u0e27\u0e02\u0e2d\u0e07\u0e1c\u0e31\u0e01\u0e01\u0e32\u0e14\u0e41\u0e01\u0e49\u0e27\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e25\u0e32\u0e22\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e31\u0e01\u0e01\u0e32\u0e14\u0e41\u0e01\u0e49\u0e27\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e04\u0e48\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e31\u0e01\u0e22\u0e31\u0e07\u0e2a\u0e14\u0e01\u0e23\u0e2d\u0e1a\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e15\u0e49\u0e19\u0e40\u0e25\u0e22 \u0e2a\u0e48\u0e27\u0e19\u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35\u0e01\u0e47\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e01\u0e30\u0e2b\u0e25\u0e48\u0e33\u0e1b\u0e25\u0e35\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e21\u0e35\u0e14\u0e2b\u0e31\u0e48\u0e19\u0e02\u0e31\u0e49\u0e27\u0e2d\u0e2d\u0e01\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e07\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19\u0e08\u0e49\u0e32<\/p>\n<h3>\u0e15\u0e49\u0e19\u0e2b\u0e2d\u0e21 , \u0e1c\u0e31\u0e01\u0e0a\u0e35 , \u0e02\u0e36\u0e49\u0e19\u0e09\u0e48\u0e32\u0e22<\/h3>\n<p>\u0e1e\u0e2d\u0e40\u0e23\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e49\u0e19\u0e2b\u0e2d\u0e21 , \u0e1c\u0e31\u0e01\u0e0a\u0e35 , \u0e02\u0e36\u0e49\u0e19\u0e09\u0e48\u0e32\u0e22\u0e21\u0e32\u0e08\u0e32\u0e01\u0e15\u0e25\u0e32\u0e14 \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e08\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e21\u0e19\u0e49\u0e33\u0e21\u0e32\u0e08\u0e19\u0e1c\u0e31\u0e01\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e0a\u0e38\u0e48\u0e21 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e23\u0e23\u0e30\u0e27\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e23\u0e01\u0e40\u0e25\u0e22\u0e04\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01\u0e43\u0e2a\u0e48\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1c\u0e31\u0e01\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e2d\u0e22\u0e39\u0e48 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e22\u0e43\u0e19\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19\u0e08\u0e30\u0e22\u0e34\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e23\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e31\u0e01\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e40\u0e19\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e04\u0e27\u0e23\u0e19\u0e33\u0e21\u0e32\u0e1c\u0e36\u0e48\u0e07\u0e25\u0e21\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e14\u0e47\u0e14\u0e43\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e19\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b \u0e01\u0e48\u0e2d\u0e19\u0e19\u0e33\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e2b\u0e48\u0e2d\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2a\u0e48\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e35\u0e48\u0e1d\u0e32\u0e1b\u0e34\u0e14\u0e21\u0e34\u0e14\u0e0a\u0e34\u0e14 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e44\u0e14\u0e49 1 \u2013 2 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30<\/p>\n<h3>\u0e1c\u0e31\u0e01\u0e1a\u0e38\u0e49\u0e07<\/h3>\n<p>\u0e16\u0e49\u0e32\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e43\u0e08\u0e14\u0e35\u0e41\u0e16\u0e21\u0e23\u0e32\u0e01\u0e15\u0e34\u0e14\u0e21\u0e32\u0e01\u0e31\u0e1a\u0e1c\u0e31\u0e01\u0e1a\u0e38\u0e49\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e27\u0e25\u0e32\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e48\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19\u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e23\u0e32\u0e01\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e38\u0e21\u0e14\u0e49\u0e27\u0e22\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30 \u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e43\u0e2b\u0e49\u0e1c\u0e31\u0e01\u0e1a\u0e38\u0e49\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e2a\u0e14\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01 2 \u0e27\u0e31\u0e19\u0e40\u0e25\u0e22\u0e19\u0e30 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e14\u0e1e\u0e23\u0e32\u0e01\u0e23\u0e32\u0e01\u0e2b\u0e32\u0e22\u0e44\u0e1b\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e48\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e31\u0e14\u0e1b\u0e32\u0e01\u0e16\u0e38\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19\u0e19\u0e30\u0e04\u0e30 \u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e31\u0e01\u0e1a\u0e38\u0e49\u0e07\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e30\u0e22\u0e34\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e31\u0e01\u0e40\u0e19\u0e48\u0e32\u0e40\u0e23\u0e47\u0e27\u0e08\u0e49\u0e32<\/p>\n<h3>\u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01<\/h3>\n<p>\u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e44\u0e27\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e21\u0e32\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30 \u0e15\u0e2d\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e22\u0e31\u0e07\u0e02\u0e32\u0e27\u0e46 \u0e2a\u0e27\u0e22\u0e46 \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e25\u0e22 \u0e40\u0e1c\u0e25\u0e2d\u0e27\u0e32\u0e07\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e41\u0e1b\u0e4a\u0e1b\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2d\u0e49\u0e32\u0e27\u0e27!! \u0e2a\u0e35\u0e40\u0e1b\u0e25\u0e35\u0e22\u0e19\u0e0b\u0e30\u0e41\u0e25\u0e49\u0e27\u0e14\u0e39\u0e44\u0e21\u0e48\u0e19\u0e48\u0e32\u0e01\u0e34\u0e19\u0e40\u0e25\u0e22 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0a\u0e38\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01\u0e01\u0e47\u0e07\u0e48\u0e32\u0e22\u0e46\u0e04\u0e48\u0e30 \u0e41\u0e04\u0e48\u0e19\u0e33\u0e16\u0e31\u0e27\u0e07\u0e2d\u0e01\u0e44\u0e1b\u0e41\u0e0a\u0e48\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e1a\u0e35\u0e1a\u0e21\u0e30\u0e19\u0e32\u0e27\u0e25\u0e07\u0e44\u0e1b\u0e04\u0e23\u0e36\u0e48\u0e07\u0e0b\u0e35\u0e01 \u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49 20 \u0e19\u0e32\u0e17\u0e35 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e33\u0e44\u0e1b\u0e25\u0e49\u0e32\u0e07\u0e19\u0e49\u0e33\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e16\u0e31\u0e48\u0e27\u0e07\u0e2d\u0e01\u0e01\u0e47\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e02\u0e32\u0e27\u0e43\u0e2a\u0e19\u0e48\u0e32\u0e17\u0e32\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<\/p>\n<h3>\u0e1e\u0e23\u0e34\u0e01<\/h3>\n<p>\u0e04\u0e19\u0e44\u0e17\u0e22\u0e02\u0e32\u0e14\u0e1e\u0e23\u0e34\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e1e\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e34\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e39\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e08\u0e32\u0e19\u0e44\u0e1b \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e23\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e46\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e47\u0e14\u0e02\u0e31\u0e49\u0e27\u0e1e\u0e23\u0e34\u0e01\u0e17\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e44\u0e1b\u0e25\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e36\u0e48\u0e07\u0e25\u0e21\u0e43\u0e2b\u0e49\u0e41\u0e2b\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e19\u0e19\u0e33\u0e44\u0e1b\u0e2b\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e49\u0e07 \u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e41\u0e25\u0e49\u0e27\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01 2 \u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e40\u0e25\u0e22\u0e04\u0e48\u0e30 \u0e2d\u0e35\u0e01\u0e27\u0e34\u0e18\u0e35\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2a\u0e48\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1d\u0e32\u0e1b\u0e34\u0e14\u0e21\u0e34\u0e14\u0e0a\u0e34\u0e14\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2d\u0e32\u0e44\u0e1b\u0e41\u0e0a\u0e48\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e23\u0e34\u0e01\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e16\u0e36\u0e07 1 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e30<br \/>\n\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e1c\u0e31\u0e01\u0e17\u0e35\u0e48\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e01\u0e47\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e17\u0e32\u0e07\u0e17\u0e35\u0e14\u0e35 \u2018\u0e1c\u0e31\u0e01\u0e2a\u0e14\u2019 \u0e04\u0e27\u0e23\u0e08\u0e30\u0e01\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19 1-2 \u0e27\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e1c\u0e31\u0e01\u0e43\u0e19\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19<\/p>\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e25\u0e49\u0e32\u0e07\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e2b\u0e49\u0e2b\u0e48\u0e2d\u0e1c\u0e31\u0e01\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e21\u0e37\u0e2d\u0e41\u0e1c\u0e48\u0e19\u0e43\u0e2b\u0e0d\u0e48 <a href=\"http:\/\/thetrainerthailand.com\/home\/\"><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:4737,&quot;3&quot;:{&quot;1&quot;:0},&quot;10&quot;:2,&quot;12&quot;:0,&quot;15&quot;:&quot;arial,sans,sans-serif&quot;}\">\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14<\/span><\/a> \u0e41\u0e25\u0e49\u0e27\u0e04\u0e48\u0e2d\u0e22\u0e19\u0e33\u0e44\u0e1b\u0e41\u0e0a\u0e48\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e40\u0e2b\u0e22\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e14\u0e43\u0e2b\u0e49\u0e19\u0e32\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e40\u0e14\u0e47\u0e14\u0e1c\u0e31\u0e01\u0e43\u0e1a\u0e17\u0e35\u0e48\u0e0a\u0e49\u0e33\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e19\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e1b\u0e01\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e19\u0e30\u0e04\u0e30..<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08 <a href=\"https:\/\/www.facebook.com\/MindsetPropertyByMin\"><strong>\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49<\/strong><\/a>\u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e17\u0e39\u0e1b\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCnzGgprXhTHkdWEcSdS9ZQw\/featured\"><strong>\u0e2a\u0e21\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32<\/strong><\/a>\u00a0\u0e41\u0e25\u0e30 \u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u00a0<strong><a href=\"https:\/\/www.thetrainerthailand.com\/\" rel=\"home\">\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07<\/a><\/strong><\/p>\n<p style=\"text-align: center;\">* * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * *<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40 <a class=\"read-more-link\" href=\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":4501,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[4],"tags":[111,18],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/title>\n<meta name=\"description\" content=\"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thetrainerthailand.com\/home\/\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14-10\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thetrainerthailand.com\/home\/\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14-10\/\" \/>\n<meta property=\"og:site_name\" content=\"The Trainer Thailand\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-11T08:28:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-02T14:25:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e42\u0e1b\u0e40\u0e15\u0e49\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/\",\"name\":\"The Trainer Thailand\",\"description\":\"Property Dealer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#primaryimage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg\",\"contentUrl\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg\",\"width\":1000,\"height\":667,\"caption\":\"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#webpage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/\",\"name\":\"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\",\"isPartOf\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#primaryimage\"},\"datePublished\":\"2018-12-11T08:28:05+00:00\",\"dateModified\":\"2021-10-02T14:25:48+00:00\",\"author\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\"},\"description\":\"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30\",\"breadcrumb\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thetrainerthailand.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\",\"name\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"caption\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\"},\"url\":\"https:\/\/thetrainerthailand.com\/home\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19","description":"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thetrainerthailand.com\/home\/\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14-10\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19","og_description":"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30","og_url":"https:\/\/thetrainerthailand.com\/home\/\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14-10\/","og_site_name":"The Trainer Thailand","article_published_time":"2018-12-11T08:28:05+00:00","article_modified_time":"2021-10-02T14:25:48+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Written by":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/thetrainerthailand.com\/home\/#website","url":"https:\/\/thetrainerthailand.com\/home\/","name":"The Trainer Thailand","description":"Property Dealer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#primaryimage","url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg","contentUrl":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2018\/12\/shutterstock_529039039.jpg","width":1000,"height":667,"caption":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14"},{"@type":"WebPage","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#webpage","url":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/","name":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19","isPartOf":{"@id":"https:\/\/thetrainerthailand.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#primaryimage"},"datePublished":"2018-12-11T08:28:05+00:00","dateModified":"2021-10-02T14:25:48+00:00","author":{"@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d"},"description":"\u0e27\u0e34\u0e18\u0e35\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14\u00a0\u0e44\u0e21\u0e48\u0e40\u0e2b\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e2a\u0e35\u0e22\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e47\u0e19\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e22\u0e46 \u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e27\u0e49 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e01\u0e34\u0e19\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e19\u0e30","breadcrumb":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thetrainerthailand.com\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e14\u0e49\u0e19\u0e32\u0e19\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19"}]},{"@type":"Person","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d","name":"\u0e42\u0e1b\u0e40\u0e15\u0e49","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","caption":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"url":"https:\/\/thetrainerthailand.com\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/4500"}],"collection":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/comments?post=4500"}],"version-history":[{"count":2,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/4500\/revisions"}],"predecessor-version":[{"id":5804,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/4500\/revisions\/5804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media\/4501"}],"wp:attachment":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media?parent=4500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/categories?post=4500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/tags?post=4500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}