{"id":5091,"date":"2019-02-17T03:55:58","date_gmt":"2019-02-17T03:55:58","guid":{"rendered":"http:\/\/thetrainerthailand.com\/home\/?p=5091"},"modified":"2021-08-12T03:10:26","modified_gmt":"2021-08-12T03:10:26","slug":"%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8","status":"publish","type":"post","link":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/","title":{"rendered":"\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<h1>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e19\u0e35\u0e49\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32<\/h1>\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e08\u0e38\u0e14\u0e44\u0e2b\u0e19\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e1a\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e15\u0e48\u0e25\u0e30\u0e08\u0e38\u0e14\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a <strong>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32<\/strong> \u0e44\u0e1b\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 8 \u0e08\u0e38\u0e14\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\u0e04\u0e31\u0e1a<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5092\" src=\"http:\/\/thetrainerthailand.com\/home\/\/wp-content\/uploads\/2019\/02\/70.jpg\" alt=\"\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\" width=\"625\" height=\"416\" srcset=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/70.jpg 625w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/70-300x200.jpg 300w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/70-500x333.jpg 500w\" sizes=\"(max-width: 625px) 100vw, 625px\" \/><\/p>\n<p><strong>1.\u0e01\u0e23\u0e30\u0e14\u0e34\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19<\/strong> \u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e19\u0e32\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e43\u0e08 \u0e01\u0e23\u0e30\u0e14\u0e34\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e19\u0e21\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e14\u0e31\u0e07<\/p>\n<p><strong>2.\u0e23\u0e39\u0e1b\u0e21\u0e49\u0e32 8 \u0e15\u0e31\u0e27<\/strong> \u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e21\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e1e\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e27\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e48\u0e27\u0e19\u0e40\u0e25\u0e02 8 \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e08\u0e1a\u0e2a\u0e34\u0e49\u0e19<\/p>\n<p><strong>3.\u0e15\u0e49\u0e19\u0e44\u0e1c\u0e48<\/strong> \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e1c\u0e48\u0e44\u0e27\u0e49\u0e02\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e1c\u0e48\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e49\u0e27\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e21\u0e49\u0e21\u0e07\u0e04\u0e25\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e15\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32<\/p>\n<p><strong>4.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 111<\/strong> \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e32\u0e14\u0e39\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e41\u0e23\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22 \u0e15\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e21\u0e35\u0e04\u0e19\u0e21\u0e32\u0e14\u0e39\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e23\u0e07\u0e43\u0e08 \u0e40\u0e25\u0e02\u0e2a\u0e27\u0e22 \u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e27\u0e48\u0e32<a href=\"https:\/\/thetrainerthailand.com\/home\">\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49<\/a>\u0e0b\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e49\u0e41\u0e15\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e19\u0e31\u0e48\u0e19\u0e21\u0e32\u0e19\u0e35\u0e48\u0e15\u0e25\u0e2d\u0e14<\/p>\n<p><strong>5.\u0e1b\u0e25\u0e32 \u0e21\u0e35\u0e19\u0e49\u0e33\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e1b\u0e25\u0e32<\/strong><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-5093\" src=\"http:\/\/thetrainerthailand.com\/home\/\/wp-content\/uploads\/2019\/02\/71.jpg\" alt=\"\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\" width=\"600\" height=\"360\" srcset=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/71.jpg 600w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/71-300x180.jpg 300w, https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/71-500x300.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>6.\u0e15\u0e49\u0e19\u0e23\u0e31\u0e01\u0e41\u0e23\u0e01\u0e1e\u0e1a<\/strong> \u0e44\u0e21\u0e49\u0e21\u0e07\u0e04\u0e25\u0e2d\u0e35\u0e01 1 \u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e25\u0e39\u0e01\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e39\u0e17\u0e35\u0e48\u0e43\u0e04\u0e23\u0e40\u0e2b\u0e47\u0e19\u0e43\u0e04\u0e23\u0e01\u0e47\u0e0a\u0e2d\u0e1a \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e21\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e32\u0e23\u0e32<\/p>\n<p><strong>7.\u0e40\u0e15\u0e48\u0e32\u0e2b\u0e07\u0e32\u0e22\u0e17\u0e49\u0e2d\u0e07<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e35\u0e48\u0e0b\u0e34\u0e19\u0e41\u0e2a\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e14\u0e27\u0e07\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 3-4 \u0e1b\u0e35\u0e19\u0e35\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e2d\u0e30\u0e44\u0e23\u0e15\u0e34\u0e14\u0e02\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e40\u0e15\u0e48\u0e32\u0e21\u0e32\u0e27\u0e32\u0e07\u0e2b\u0e07\u0e32\u0e22\u0e17\u0e49\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e15\u0e23\u0e07\u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e19\u0e2d\u0e19\u0e2b\u0e07\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e19\u0e35\u0e49 \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e2b\u0e47\u0e19\u0e19\u0e36\u0e01\u0e27\u0e48\u0e32\u0e27\u0e32\u0e07\u0e1c\u0e34\u0e14 \u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e1e\u0e25\u0e34\u0e01\u0e43\u0e2b\u0e49 \u0e08\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2d\u0e32\u0e2a\u0e01\u0e47\u0e2d\u0e15\u0e40\u0e17\u0e1b\u0e21\u0e32\u0e41\u0e1b\u0e30\u0e22\u0e36\u0e14\u0e44\u0e27\u0e49\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19<\/p>\n<p><strong>8.\u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e21\u0e35\u0e19\u0e49\u0e33\u0e44\u0e2b\u0e25\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32<\/strong> \u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e40\u0e27\u0e35\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e23\u0e32\u0e1a\u0e23\u0e37\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e15\u0e34\u0e14\u0e02\u0e31\u0e14<\/p>\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08 <a href=\"https:\/\/www.facebook.com\/MindsetPropertyByMin\"><strong>\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49<\/strong><\/a>\u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e17\u0e39\u0e1b\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCnzGgprXhTHkdWEcSdS9ZQw\/featured\"><strong>\u0e2a\u0e21\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32<\/strong><\/a>\u00a0\u0e41\u0e25\u0e30 \u0e2b\u0e19\u0e49\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u00a0<strong><a href=\"https:\/\/www.thetrainerthailand.com\/\" rel=\"home\">\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07<\/a><\/strong><\/p>\n<p style=\"text-align: center;\">* * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * * *<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a  <a class=\"read-more-link\" href=\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":5095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[4],"tags":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/title>\n<meta name=\"description\" content=\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thetrainerthailand.com\/home\/\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-8-\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thetrainerthailand.com\/home\/\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-8-\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\/\" \/>\n<meta property=\"og:site_name\" content=\"The Trainer Thailand\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-17T03:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-12T03:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e42\u0e1b\u0e40\u0e15\u0e49\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/\",\"name\":\"The Trainer Thailand\",\"description\":\"Property Dealer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#primaryimage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg\",\"contentUrl\":\"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg\",\"width\":800,\"height\":600,\"caption\":\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#webpage\",\"url\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/\",\"name\":\"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\",\"isPartOf\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#primaryimage\"},\"datePublished\":\"2019-02-17T03:55:58+00:00\",\"dateModified\":\"2021-08-12T03:10:26+00:00\",\"author\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\"},\"description\":\"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49\",\"breadcrumb\":{\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/thetrainerthailand.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d\",\"name\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g\",\"caption\":\"\u0e42\u0e1b\u0e40\u0e15\u0e49\"},\"url\":\"https:\/\/thetrainerthailand.com\/home\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22","description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thetrainerthailand.com\/home\/\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-8-\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22","og_description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49","og_url":"https:\/\/thetrainerthailand.com\/home\/\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c-8-\u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\/","og_site_name":"The Trainer Thailand","article_published_time":"2019-02-17T03:55:58+00:00","article_modified_time":"2021-08-12T03:10:26+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Written by":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/thetrainerthailand.com\/home\/#website","url":"https:\/\/thetrainerthailand.com\/home\/","name":"The Trainer Thailand","description":"Property Dealer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thetrainerthailand.com\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#primaryimage","url":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg","contentUrl":"https:\/\/thetrainerthailand.com\/home\/wp-content\/uploads\/2019\/02\/72.jpg","width":800,"height":600,"caption":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32"},{"@type":"WebPage","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#webpage","url":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/","name":"\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22","isPartOf":{"@id":"https:\/\/thetrainerthailand.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#primaryimage"},"datePublished":"2019-02-17T03:55:58+00:00","dateModified":"2021-08-12T03:10:26+00:00","author":{"@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d"},"description":"\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e35\u0e46\u0e19\u0e33\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e01\u0e31\u0e19\u0e04\u0e31\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e43\u0e0a\u0e49","breadcrumb":{"@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thetrainerthailand.com\/home\/%e0%b8%95%e0%b8%b2%e0%b8%a1%e0%b8%95%e0%b8%b3%e0%b8%a3%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-8-%e0%b8%88%e0%b8%b8%e0%b8%94%e0%b8%ae%e0%b8%a7%e0%b8%87%e0%b8%88%e0%b8%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thetrainerthailand.com\/home\/"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e27\u0e47\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 8 \u0e08\u0e38\u0e14\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e41\u0e25\u0e49\u0e27\u0e14\u0e35 \u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22"}]},{"@type":"Person","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/39be4153d82ea7ef666dd7554732a61d","name":"\u0e42\u0e1b\u0e40\u0e15\u0e49","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/thetrainerthailand.com\/home\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15cf05ceb9fc4897cd8a508d4df6d56f?s=96&d=mm&r=g","caption":"\u0e42\u0e1b\u0e40\u0e15\u0e49"},"url":"https:\/\/thetrainerthailand.com\/home\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/5091"}],"collection":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/comments?post=5091"}],"version-history":[{"count":4,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/5091\/revisions"}],"predecessor-version":[{"id":5648,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/posts\/5091\/revisions\/5648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media\/5095"}],"wp:attachment":[{"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/media?parent=5091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/categories?post=5091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thetrainerthailand.com\/home\/wp-json\/wp\/v2\/tags?post=5091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}